{"id":17688,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/marileidy-paulino-a-un-paso-de-su-primer-oro-mundialista-2\/"},"modified":"1970-01-01T00:00:00","modified_gmt":"1970-01-01T00:00:00","slug":"marileidy-paulino-a-un-paso-de-su-primer-oro-mundialista-2","status":"publish","type":"post","link":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/marileidy-paulino-a-un-paso-de-su-primer-oro-mundialista-2\/","title":{"rendered":"Marileidy Paulino, a un paso de su primer oro mundialista"},"content":{"rendered":"<p>La tarde de este mi\u00e9rcoles, <strong>Marileidy Paulino<\/strong> persigue la que ser\u00eda su medalla m\u00e1s importante en un campeonato mundial.<\/p>\n<p>Su gran momento ser\u00e1 a las 3:35 p.m., hora de Rep\u00fablica Dominicana (9:35 p.m., en Hungr\u00eda) en el que espera, que unos 50 segundos despu\u00e9s, o algo menos, proclamarse como al campeona de los 400 metros planos del <strong>Mundial de atletismo<\/strong> 2023.<\/p>\n<p>La dominicana saldr\u00e1 en el carril n\u00famero 7. Los puestos para las ocho corredoras est\u00e1n marcados del 2 al 9.<\/p>\n<p>Si Paulino gana el oro mundialista ser\u00e1 la primera mujer dominicana con medalla de oro en este nivel, como ya lo es con su presea de plata, tambi\u00e9n se unir\u00e1 a F\u00e9lix S\u00e1nchez como los \u00fanicos dominicanos con presea dorada en un <strong>Mundial de Atletismo<\/strong>.<\/p>\n<p><!-- ctrlPlaceHolderImagen Inicio --><\/p>\n<div class=\"expand-img-placeholder\"><span class=\"rutaimagenoriginal-placeholder\">https:\/\/resources.diariolibre.com\/images\/2023\/08\/22\/marileidy-paulinolista-de-salida-final-400-mmundial-2023-a961fda5.jpg<\/span><\/div>\n<p><span>Lista de salida de la final de los 400 metros planos del Mundial de Atletismo 2023<\/span><!-- ctrlPlaceHolderImagen Final --><\/p>\n<p>Varios rostros conocidos para Marileidy en los bloques de salida. Cuatro de ellas las vio en julio pasado en la Liga Diamante; a tres en la final del <strong>Mundial de atletismo<\/strong> 2022 y una eliminada en semifinal y de las ocho de esta final mundialista cinco estuvieron en los Juegos Ol\u00edmpicos, una finalista, tres eliminadas en semifinales y una no inici\u00f3 su carrera.<\/p>\n<p>El escenario para la anhelada proeza ser\u00e1 el Centro Nacional de Atletismo, el moderno estadio de Budapest, Hungr\u00eda, sede del campeonato, que celebra este mi\u00e9rcoles su quinto d\u00eda de competencia.<\/p>\n<p><!-- ctrlPlaceHolderImagen Inicio --><\/p>\n<div class=\"expand-img-placeholder\"><span class=\"rutaimagenoriginal-placeholder\">https:\/\/resources.diariolibre.com\/images\/2023\/08\/22\/marileidy-paulino-saluda-a-paola-moran-mex-candice-mcleod-jam-izq-tras-semifinal-1-mundial-de-atletismo-en-budapest-hungria-21-de-agosto-de-2023-ap-ashley-landis-cd40f6b8.jpg<\/span><\/div>\n<p><span>Marileidy Paulino, de la Rep\u00fablica Dominicana, en el centro toca la mano de Paola Mor\u00e1n, de M\u00e9xico, despu\u00e9s de que la dominicana se clasificara en la serie femenina de 400 metros mientras Candice Mcleod, de Jamaica, observa durante el Campeonato Mundial de Atletismo en Budapest, Hungr\u00eda, el lunes 1 de agosto. 21 de octubre de 2023.<\/span><span> (<strong>AP\/ASHLEY LANDIS<\/strong>)<\/span><!-- ctrlPlaceHolderImagen Final --><\/p>\n<p>La pista fue construida para esta competencia. Aqu\u00ed, 36 mil fan\u00e1ticos ver\u00edan su logro.<\/p>\n<p>Su prueba ser\u00e1 la pen\u00faltima final de la jornada, para luego dar paso a la carrera por el t\u00edtulo de los 400 metros con vallas.<\/p>\n<p>En el Mundial de 2022, la velocista dominicana qued\u00f3 con medalla de plata en el Hayward Field, de Eugene, Oregon, Estados Unidos, luego de que la bahame\u00f1a, Shaunae Miller-Uibo se hizo del oro.<\/p>\n<p>La atleta quisqueyana ha estado dominante en sus carreras tanto la preliminar, como en la semifinal. Solo le falta dar el zarpazo de la final.<\/p>\n<div class=\"w-full pt-2 float-left inside-related\">    <span class=\"border-b border-black pb-3 mb-4 block\"><strong>RELACIONADAS<\/strong><\/span>                                \n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/08\/21\/mundial-de-atletismo-marileidy-se-pone-a-un-paso-del-oro\/2437962?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\" title=\"Olimpismo\">Olimpismo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/08\/21\/mundial-de-atletismo-marileidy-se-pone-a-un-paso-del-oro\/2437962?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Marileidy Paulino, a un paso de su sue\u00f1o dorado, avanza a la final de los 400 metros\">Marileidy Paulino, a un paso de su sue\u00f1o dorado, avanza a la final de los 400 metros<\/a><\/h2>\n<\/div>\n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/07\/16\/marileidy-paulino-pierde-por-primera-vez-en-liga-diamante\/2404969?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\" title=\"Olimpismo\">Olimpismo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/07\/16\/marileidy-paulino-pierde-por-primera-vez-en-liga-diamante\/2404969?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Marileidy Paulino pierde por primera vez en la Liga Diamante\">Marileidy Paulino pierde por primera vez en la Liga Diamante<\/a><\/h2>\n<\/div>\n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/06\/09\/marileidy-paulino-da-credito-a-fortaleza-mental-para-triunfo\/2340826?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\" title=\"Olimpismo\">Olimpismo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/deportes\/olimpismo\/2023\/06\/09\/marileidy-paulino-da-credito-a-fortaleza-mental-para-triunfo\/2340826?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Marileidy Paulino da cr\u00e9dito a la fortaleza mental para lograr \u00e9pica victoria\">Marileidy Paulino da cr\u00e9dito a la fortaleza mental para lograr \u00e9pica victoria<\/a><\/h2>\n<\/div>\n<\/div>\n<p>Paulino tiene la segunda mejor marca del a\u00f1o con sus 48.98 en Los Angeles, California, el pasado 27de mayo, por detr\u00e1s de los 48.74 de la estadounidense Sydney McLaughlin-Levrone, establecido el pasado 8 de julio en Eugene, Oregon, la plaza donde la dominicana gan\u00f3 la plata el pasado a\u00f1o.<\/p>\n<p>McLaughlin-Levrone declin\u00f3 participar en este campeonato mundial alegando molestias. Ella es due\u00f1a de la d\u00e9cima mejor marca de todos los tiempos.<\/p>\n<p>En resumen, cuatro de las nueve atletas que entrar\u00e1n a la pista del Estadio son parte de las 10 mejores marcas de la distancia en este 2023.<\/p>\n<p>Dentro de ese grupo est\u00e1 <strong>Natalia Kaczmarek<\/strong> (Polonia), quien saldr\u00e1 en el carril 6. Fue\u00a0Kaczmarek la que con un registro de\u00a049,48 venci\u00f3 a Paulino en el Meeting\u00a0Memorial Kamili de Silesia, de la Liga Diamante, el pasado 16 de julio.<\/p>\n<p><!-- ctrlPlaceHolderImagen Inicio --><\/p>\n<div class=\"expand-img-placeholder\"><span class=\"rutaimagenoriginal-placeholder\">https:\/\/resources.diariolibre.com\/images\/2023\/08\/22\/marileidy-paulino-c9e5be46.jpg<\/span><\/div>\n<p><span>Resultados de las tres semifinales del Mundial de Atletismo 2023 el pasado 20 de agosto.<\/span><!-- ctrlPlaceHolderImagen Final --><\/p>\n<p>No ser\u00e1 el \u00fanico rostro conocido para Paulino. En pista con ella tambi\u00e9n correr\u00e1n, Lieke Klaver, segunda en ese\u00a0en el Meeting\u00a0Memorial Kamili (49.81), por delante de Paulino.\u00a0<\/p>\n<p>Candice McLeod tambi\u00e9n est\u00e1 en la parrilla de salida, lo har\u00e1 en el carril 3. Fue cuarta en ese citado Meeting con un tiempo de\u00a050.19.<\/p>\n<p>Sada Williams partir\u00e1 del carrill n\u00famero 8. Tambi\u00e9n estuvo en Silesia, con un quinto puesto por su\u00a050.34.<\/p>\n<p>Es la \u00faltima vez que este grupo se vio junto en una largada.<\/p>\n<p>En el Mundial pasado, McLeod, Klaver y Williams estuvieron en la final. Kaczmarek fue eliminada en semifinales.<\/p>\n<p>En los Juegos Ol\u00edmpicos, McLeod fue finalista, Klaver, Kaczmarek y Williams quedaron descartadas en semifinales y Bolingo no inici\u00f3 su heat.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La tarde de este mi\u00e9rcoles, Marileidy Paulino persigue la que ser\u00eda su medalla m\u00e1s importante en un campeonato mundial. Su gran momento ser\u00e1 a las 3:35 p.m., hora de Rep\u00fablica Dominicana (9:35 p.m.,&#8230;<\/p>\n","protected":false},"author":0,"featured_media":17689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/17688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/comments?post=17688"}],"version-history":[{"count":0,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/17688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media\/17689"}],"wp:attachment":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media?parent=17688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/categories?post=17688"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/tags?post=17688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}