{"id":61684,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/470-personas-tienen-salarios-que-superan-el-millon-de-pesos-en-la-tss-9\/"},"modified":"1970-01-01T00:00:00","modified_gmt":"1970-01-01T00:00:00","slug":"470-personas-tienen-salarios-que-superan-el-millon-de-pesos-en-la-tss-9","status":"publish","type":"post","link":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/470-personas-tienen-salarios-que-superan-el-millon-de-pesos-en-la-tss-9\/","title":{"rendered":"470 personas tienen salarios que superan el mill\u00f3n de pesos en la TSS"},"content":{"rendered":"<p>A junio de 2024, solo 470 <strong><\/strong><strong><\/strong><strong>empleados<\/strong>, que cotizan en el Sistema Dominicano de la <strong>Seguridad Social<\/strong> (SDSS), devengan <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> que superan el mill\u00f3n de pesos cada mes, dentro de un universo de 2,319,600 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong>. En junio de 2019, eran 174 las personas que recib\u00edan ingresos de seis cifras mensualmente, por lo cual los asalariados millonarios han crecido m\u00e1s del doble, cinco a\u00f1os despu\u00e9s. <\/p>\n<p>En un pa\u00eds con ingresos promedio bajos, resalta el dato de que m\u00e1s de 81,000 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong> devengan <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> entre 100,000 y un mill\u00f3n de pesos. La data que entreg\u00f3 la Tesorer\u00eda de la <strong>Seguridad Social<\/strong> (<strong>TSS<\/strong>) a Diario Libre muestra que hay 1,479 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong> que reciben <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> entre 500,000 y 700,000 pesos y 750 <strong><\/strong><strong><\/strong><strong>empleados<\/strong> son receptores de remuneraciones entre 700,000 y un mill\u00f3n de pesos.<\/p>\n<p>La <strong>TSS<\/strong> destaca que para el c\u00e1lculo de la masa salarial cotizable y de los promedios de ingresos, solo se toman en cuenta los <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> hasta el tope m\u00e1ximo de cotizaci\u00f3n equivalente a 20 <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> m\u00ednimos. Adem\u00e1s, la media corresponde a los <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> m\u00ednimos del sector privado no sectorizado establecidos por el Comit\u00e9 Nacional de Salarios.<\/p>\n<h2><strong>Ingresos por sector<\/strong><\/h2>\n<p>En cambio, el portal de la <strong>TSS<\/strong>, con datos registrados hasta mayo de 2024, indica que el SDSS registr\u00f3 aproximadamente 2,301,617 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong> y un total de 2,393,655 <strong><\/strong><strong>cotizaciones<\/strong> con un <strong>salario<\/strong> promedio cotizable de 34,595.91 pesos.<\/p>\n<p>En t\u00e9rminos de <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong>, el subsector de explotaci\u00f3n de minas y canteras presenta el promedio m\u00e1s alto, con 73,480.60 pesos. Sin embargo, este subsector representa solo el 0.3 % del total de <strong><\/strong><strong><\/strong><strong>empleados<\/strong> cotizantes, es decir, 6,716 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong>.<\/p>\n<p>Por otro lado, un grupo de 4,083 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong>, que equivale al 0.2 % del total, tiene el <strong>salario<\/strong> promedio cotizable m\u00e1s bajo, de 16,156.10 pesos. La publicaci\u00f3n de la <strong>TSS<\/strong> no especifica el sector al que pertenecen estos <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong>.<\/p>\n<p>El Bolet\u00edn estad\u00edstico del R\u00e9gimen contributivo del SDSS muestra que, durante el mes de mayo, el 53.33 % de las <strong><\/strong><strong>cotizaciones<\/strong> correspondieron a hombres y el 46.67 % a mujeres. Las trabajadoras tuvieron un <strong>salario<\/strong> promedio cotizable de 35,579.65 pesos, ligeramente superior al promedio de los hombres, que fue de 35,003.14 pesos.<\/p>\n<div class=\"social-embed mb-4\">\n<div class=\"placeholderYoutube\">\n<div><a class='flourish-credi lazy\" href=' target=\"_top\" title=\" \" rel=\"noopener\"> <\/a><\/div>\n<\/div>\n<\/div>\n<p>La mayor proporci\u00f3n de <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong> cotizantes se encuentra en el rango de edad de 31 a 55 a\u00f1os, que representa el 55.23 % del total registrado. Este grupo etario tambi\u00e9n exhibe el <strong>salario<\/strong> promedio cotizable m\u00e1s alto, alcanzando 39,346.64 pesos. <\/p>\n<p>En cuanto a la distribuci\u00f3n de las <strong><\/strong><strong>cotizaciones<\/strong> por rango salarial, el 49.59 % se encuentra en el intervalo de 15,000 a 30,000 pesos. Los <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> entre 30,000 y 50,000 pesos abarcan el 16.68 % de las <strong><\/strong><strong>cotizaciones<\/strong>, mientras que los <strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong><\/strong><strong>salarios<\/strong> superiores a 50,000 pesos constituyen el 16.02 % del total que indica el SDSS.<\/p>\n<p>Respecto al tama\u00f1o de los <strong>empleadores<\/strong>, el 61.81 % de <strong>las cotizacione<\/strong>s provienen de empresas con m\u00e1s de 150 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong>. Las empresas con entre 11 y 50 <strong><\/strong><strong><\/strong><strong>empleados<\/strong> concentran el 16.51 % de las <strong><\/strong><strong>cotizaciones<\/strong>, mientras que aquellas con hasta 10 <strong><\/strong><strong><\/strong><strong>trabajadores<\/strong> contribuyen con el 12.04 %. Las empresas con entre 51 y 150 <strong><\/strong><strong><\/strong><strong>empleados<\/strong> representan el 9.65 % de las <strong><\/strong><strong>cotizaciones<\/strong>.<\/p>\n<div class=\"w-full pt-2 float-left inside-related\">    <span class=\"border-b border-black pb-3 mb-4 block\"><strong>RELACIONADAS<\/strong><\/span>                                \n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/economia\/finanzas\/2024\/07\/26\/como-operaba-el-fraude-a-la-tss-y-las-aseguradoras-de-salud\/2799125?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/economia\/finanzas\" title=\"Finanzas\">Finanzas<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/economia\/finanzas\/2024\/07\/26\/como-operaba-el-fraude-a-la-tss-y-las-aseguradoras-de-salud\/2799125?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Fraude a la TSS: aseguraban a falsos empleados con enfermedades de alto costo\">Fraude a la TSS: aseguraban a falsos empleados con enfermedades de alto costo<\/a><\/h2>\n<\/div>\n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/economia\/empleo\/2024\/07\/07\/mujeres-siguen-con-mejor-salario-promedio-en-la-seguridad-social\/2778660?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/economia\/empleo\" title=\"Empleo\">Empleo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/economia\/empleo\/2024\/07\/07\/mujeres-siguen-con-mejor-salario-promedio-en-la-seguridad-social\/2778660?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Hombres siguen encabezando la Seguridad Social, pero las mujeres mantienen mejor salario promedio\">Hombres siguen encabezando la Seguridad Social, pero las mujeres mantienen mejor salario promedio<\/a><\/h2>\n<\/div>\n<\/div>\n<h2>Brecha salarial en RD<\/h2>\n<p>Seg\u00fan el Bolet\u00edn anual de Pobreza Monetaria 2023 del Ministerio de Econom\u00eda, Planificaci\u00f3n y Desarrollo (Mepyd), la tasa de <strong><\/strong><strong>pobreza<\/strong> <strong><\/strong><strong>monetaria<\/strong> general en 2023 fue del 23.0 %, una disminuci\u00f3n significativa de 4.7 puntos porcentuales respecto al 27.7 % registrado en 2022.<\/p>\n<p>En el primer trimestre de 2024, la tasa de <strong><\/strong><strong>pobreza<\/strong> <strong><\/strong><strong>monetaria<\/strong> continu\u00f3 su descenso, alcanzando un 18.9 %, una reducci\u00f3n de 5.3 puntos porcentuales en comparaci\u00f3n con el primer trimestre de 2023.<\/p>\n<p>    El porcentaje del trimestre octubre-diciembre 2023 es inferior a los niveles observados antes de<strong> la pandemia <\/strong>(2016-2019).<\/p>\n<p>En el primer trimestre de 2024, la<strong> tasa de <\/strong><strong><\/strong><strong>pobreza<\/strong> <strong><\/strong><strong>monetaria<\/strong> continu\u00f3 su descenso, alcanzando un 18.9 %, una reducci\u00f3n de 5.3 puntos porcentuales en comparaci\u00f3n con el primer trimestre de 2023. En comparaci\u00f3n con el periodo prepandemia, esta disminuci\u00f3n representa 18.7 puntos porcentuales menos que en el trimestre enero-marzo de 2016 y 7.2 puntos porcentuales menos que en el trimestre enero-marzo de 2019.<\/p>\n<h2>Retrato de la <strong>desigualdad<\/strong> en AL <\/h2>\n<p>De acuerdo con el estudio del Banco Interamericano de Desarrollo (BID): \u201cLa crisis de la <strong>desigualdad<\/strong>, <strong>Am\u00e9rica<\/strong> Latina y el Caribe en la encrucijada\u201d, <strong>Am\u00e9rica<\/strong> Latina y el Caribe es una de las regiones m\u00e1s desiguales del mundo en t\u00e9rminos de ingresos.<\/p>\n<p>     El 10 % m\u00e1s rico de la poblaci\u00f3n capta 22 veces m\u00e1s de la renta nacional que el 10 % m\u00e1s pobre.<\/p>\n<p>Adem\u00e1s, el 1 % de los m\u00e1s ricos obtiene el 21 % de los ingresos de toda la econom\u00eda, el doble de la media en los pa\u00edses industrializados. Estas diferencias en ingresos representan solo una parte de <strong>la <\/strong><strong>desigualdad<\/strong> que afecta la cohesi\u00f3n social y el sentido de pertenencia.<\/p>","protected":false},"excerpt":{"rendered":"<p>A junio de 2024, solo 470 empleados, que cotizan en el Sistema Dominicano de la Seguridad Social (SDSS), devengan salarios que superan el mill\u00f3n de pesos cada mes, dentro de un universo de&#8230;<\/p>\n","protected":false},"author":0,"featured_media":61644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/61684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/comments?post=61684"}],"version-history":[{"count":0,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/61684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media\/61644"}],"wp:attachment":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media?parent=61684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/categories?post=61684"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/tags?post=61684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}