{"id":63166,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/punta-bergantin-relanzara-turismo-de-puerto-plata-y-zona-norte-de-rd-6\/"},"modified":"1970-01-01T00:00:00","modified_gmt":"1970-01-01T00:00:00","slug":"punta-bergantin-relanzara-turismo-de-puerto-plata-y-zona-norte-de-rd-6","status":"publish","type":"post","link":"http:\/\/joelaybar.com\/wp\/1970\/01\/01\/punta-bergantin-relanzara-turismo-de-puerto-plata-y-zona-norte-de-rd-6\/","title":{"rendered":"Punta Bergant\u00edn relanzar\u00e1 turismo de Puerto Plata y zona norte de RD"},"content":{"rendered":"<p>Con la presencia del presidente de la Rep\u00fablica, <strong>Luis Abinader<\/strong>, se dio ayer el primer picazo del <strong>Hotel<\/strong> <strong><\/strong><strong>Hyatt<\/strong> Zilara, del proyecto tur\u00edstico <strong>Punta Bergant\u00edn<\/strong>, iniciativa que pretende relanzar esta ciudad como destino.<\/p>\n<p>\u201cEstoy convencido de que hoy representa un cambio para la regi\u00f3n. Desde el 2002, <strong>Puerto Plata<\/strong> ha ca\u00eddo, pero tengo toda la confianza de que hoy es un punto de inflexi\u00f3n donde vamos a crecer a partir de estas acciones. Necesit\u00e1bamos marcas americanas para atraer esos turistas estadounidenses y aqu\u00ed estamos con <strong><\/strong><strong>Hyatt<\/strong>\u201d, dijo el presidente <strong>Luis Abinader<\/strong>.<\/p>\n<p>\u201cCreo que este proyecto va m\u00e1s all\u00e1 del desarrollo tur\u00edstico de los 10 millones de metros cuadrados, habr\u00e1 un impacto en toda la regi\u00f3n y podemos asegurarles a los inversionistas que contar\u00e1n con el apoyo del Gobierno en t\u00e9rminos de obras p\u00fablicas, promoci\u00f3n y todo lo dem\u00e1s\u201d, agreg\u00f3. El mandatario dijo que con <strong>Punta Bergant\u00edn<\/strong> \u201choy relanzamos <strong>Puerto Plata<\/strong>\u201d.<\/p>\n<div class=\"my-12 component cifra relative border bg-component\">    <span class=\"text-xl block my-3 component-title glosa\"><strong><\/strong><\/span>    \n<p class=\"insert-subtitle\">\n<\/p>\n<div class=\"relative block mb-3\"><span class=\"float-left mr-2 cifra-number glosa\">20 mil<\/span><span class=\"cifra-description glosa\"><\/span><\/div>\n<p>Son los empleos que generar\u00e1 el proyecto, el cual se aliar\u00e1 al Infotep para la formaci\u00f3n de los recursos humanos<\/p>\n<\/div>\n<p><\/p>\n<p>En el acto estuvieron presentes los presidentes del <strong>Senado<\/strong> y la <strong>C\u00e1mara de Diputados<\/strong>, Ricardo De los Santos y Alfredo Pacheco, respectivamente. Adem\u00e1s, el gobernador del <strong>Banco Central<\/strong>, H\u00e9ctor Valdez Albizu; el ministro de <strong>Turismo<\/strong>, David Collado; el presidente ejecutivo del Banco de Reservas, Samuel Pereyra y otros funcionarios.<\/p>\n<p>Antonio Fungairino, director de Desarrollo de <strong>Inclusive Collection<\/strong> de <strong><\/strong><strong>Hyatt<\/strong> para <strong>Am\u00e9rica Latina<\/strong> y el Caribe, manifest\u00f3 en el acto la apuesta de la corporaci\u00f3n al crecimiento del destino <strong>Puerto Plata<\/strong>, con todos los atractivos que re\u00fane en el norte de la isla, en la llamada costa dorada.<\/p>\n<p>\u201cPara nosotros esta comunidad de <strong>Villa de Monte Llano<\/strong> ser\u00e1 transformada a trav\u00e9s del <strong>turismo<\/strong>, con este desarrollo\u201d, dijo, a su vez,\u00a0 Andr\u00e9s Marranzini, director ejecutivo del proyecto.<\/p>\n<p>Este desarrollo forma parte de los planes del Gobierno para relanzar la econom\u00eda de la provincia apoy\u00e1ndose en la actividad tur\u00edstica, est\u00e1\u00a0 a cargo de un fideicomiso que encabeza el Banco de Reservas, y ocupa un \u00e1rea de 10 millones de metros cuadrados\u00a0 con un litoral marino\u00a0 y un entorno medioambiental de gran belleza. <\/p>\n<h2>Un proyecto y seis hoteles<\/h2>\n<p><strong>Punta Bergant\u00edn<\/strong> est\u00e1 ubicada a 15 minutos de <strong>Puerto Plata<\/strong>, 12 minutos de Sos\u00faa y a ocho minutos del aeropuerto internacional Gregorio Luper\u00f3n. Promueve la construcci\u00f3n de hasta seis hoteles cinco estrellas, con una oferta de 4,500 habitaciones, adem\u00e1s, 1,500 unidades vacacionales, 2,500 unidades de uso mixto y un Pueblo Marino.<\/p>\n<p>Informaron que, para la ejecuci\u00f3n de <strong>Punta Bergant\u00edn<\/strong>, se crear\u00e1n 20 mil empleos y se ha realizado una alianza con el <strong>Infotep<\/strong> para formar los recursos humanos que se necesitan.<\/p>\n<div class=\"w-full pt-2 float-left inside-related\">    <span class=\"border-b border-black pb-3 mb-4 block\"><strong>RELACIONADAS<\/strong><\/span>                                \n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\/2024\/07\/23\/conceden-licencia-ambiental-a-proyecto-turistico-punta-bergantin\/2795541?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\" title=\"Turismo\">Turismo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\/2024\/07\/23\/conceden-licencia-ambiental-a-proyecto-turistico-punta-bergantin\/2795541?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Medio Ambiente autoriza proyecto tur\u00edstico Punta Bergant\u00edn en Puerto Plata\">Medio Ambiente autoriza proyecto tur\u00edstico Punta Bergant\u00edn en Puerto Plata<\/a><\/h2>\n<\/div>\n<div class=\"xl:w-2\/12 w-4\/12\">                                                                        <a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\/2024\/01\/26\/proyecto-hotelero-de-melia-y-grupo-puntacana-en-punta-bergantin\/2588674?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"                                                                                                                            \">                                                                                                                            <\/a>                                                            <\/div>\n<div class=\"xl:w-10\/12 w-8\/12 pl-3\">\n<div class=\"text-md mb-2 meta\">                        <a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\" title=\"Turismo\">Turismo<\/a>                    <\/div>\n<h2><a href=\"https:\/\/www.diariolibre.com\/economia\/turismo\/2024\/01\/26\/proyecto-hotelero-de-melia-y-grupo-puntacana-en-punta-bergantin\/2588674?utm_source=relacionadas&amp;utm_medium=nota&amp;utm_campaign=relacionadas\" title=\"Punta Bergant\u00edn alojar\u00e1 un nuevo proyecto hotelero de Meli\u00e1 Hotels y Grupo Puntacana\">Punta Bergant\u00edn alojar\u00e1 un nuevo proyecto hotelero de Meli\u00e1 Hotels y Grupo Puntacana<\/a><\/h2>\n<\/div>\n<\/div>\n<p>Han firmado acuerdos para participar en el proyecto el <strong>Grupo Martin\u00f3n<\/strong>, que inici\u00f3 este mi\u00e9rcoles 21 de agosto su primer hotel, de la marca \u201cInclusive Colletion\u201d de <strong><\/strong><strong>Hyatt<\/strong>; un Meli\u00e1, que es una inversi\u00f3n conjunta del <strong>Hotel<\/strong> Meli\u00e1 Internacional y el Grupo <strong>Puntacana<\/strong>; un <strong>Hilton<\/strong> y un <strong>Marriot<\/strong>. <\/p>\n<p>\u201cCreemos firmemente en este proyecto y por eso estamos aqu\u00ed\u201d, manifest\u00f3 Enrique Martin\u00f3n, presidente del grupo que lleva su apellido.<\/p>\n<p>\u201cQu\u00e9 m\u00e1s confianza se necesita para este proyecto que contar con el respaldo de la familia Rainieri\u201d.<\/p>\n<p>Explic\u00f3 que en un a\u00f1o ya tendr\u00e1n disponibles 800 nuevas habitaciones, que generar\u00e1n 1,300 empleos directos y \u201cesto servir\u00e1 como un impulso a la econom\u00eda dominicana\u201d. <\/p>\n<p>Marranzini agradeci\u00f3 especialmente a la familia Rainieri, \u201ca don Frank y a Frank El\u00edas, que cuando les present\u00e9\u00a0 el proyecto me preguntaron c\u00f3mo pod\u00edan ayudarme y les dije que invirtieran en <strong>Puerto Plata<\/strong> y aqu\u00ed est\u00e1n\u201d.<\/p>\n<div class=\"my-12 component web-insert relative border bg-component\">    <span class=\"text-xl block my-3 component-title glosa\"><strong>Master plan con sostenibilidad<\/strong><\/span>    \n<p class=\"insert-subtitle\">\n<\/p><p>Punta Bergant\u00edn se ha dise\u00f1ado para preservar la belleza natural, con baja densidad urbana, combinando hoteles, \u00e1reas de esparcimiento, viviendas horizontales y verticales, promoviendo un destino inmobiliario y tur\u00edstico de primer nivel, para los visitantes, residentes e inversionistas en sus diversos componentes, entre otras estrategias ambientales.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Con la presencia del presidente de la Rep\u00fablica, Luis Abinader, se dio ayer el primer picazo del Hotel Hyatt Zilara, del proyecto tur\u00edstico Punta Bergant\u00edn, iniciativa que pretende relanzar esta ciudad como destino&#8230;.<\/p>\n","protected":false},"author":0,"featured_media":63139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/63166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/comments?post=63166"}],"version-history":[{"count":0,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/posts\/63166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media\/63139"}],"wp:attachment":[{"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/media?parent=63166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/categories?post=63166"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/joelaybar.com\/wp\/wp-json\/wp\/v2\/tags?post=63166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}